{"id":316,"date":"2021-09-01T08:15:42","date_gmt":"2021-09-01T08:15:42","guid":{"rendered":"https:\/\/www.persecution.com\/es\/historias\/?p=316"},"modified":"2022-10-21T21:21:52","modified_gmt":"2022-10-21T21:21:52","slug":"una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa","status":"publish","type":"post","link":"https:\/\/www.persecution.com\/es\/historias\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\/","title":{"rendered":"Una guardia norcoreana habla accidentalmente de Dios a una mujer presa"},"content":{"rendered":"\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>Mientras Kyung-Ja luchaba por mantener la consciencia con la cabeza ensangrentada por los repetidos golpes de un garrote escuch\u00f3 a su carcelera gritar palabras que nunca hab\u00eda o\u00eddo en sus 56 a\u00f1os de vida: \u00ab<a href=\"https:\/\/www.persecution.com\/es\/biblias\/?utm_campaign=bibles_es&amp;utm_source=ESSTORIES\">Biblia<\/a>\u00bb, \u00abDios\u00bb, \u00abJes\u00fas\u00bb.<\/em><\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"north-korean-guard-an-unlikely-evangelist\">Guardia de Corea del Norte: Evangelista por accidente<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Kyung-Ja entend\u00eda por qu\u00e9 la guardia la hab\u00eda interrogado sobre su \u00faltimo viaje a <a href=\"http:\/\/persecution.com\/es\/guiadeoracionglobal\/china\/\">China<\/a> y sobre la deserci\u00f3n de su hija a <a href=\"https:\/\/vomkorea.com\/en\/\">Corea del Sur<\/a>, pero no pod\u00eda entender por qu\u00e9 segu\u00eda haciendo preguntas extra\u00f1as sobre algo llamado \u00abcristianismo\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLa primera vez que conoc\u00ed el cristianismo fue gracias a mi torturadora\u00bb, dijo Kyung-Ja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las confusas y persistentes preguntas de la carcelera despertaron la curiosidad de Kyung-ja. En el momento de su detenci\u00f3n, no ten\u00eda ning\u00fan sistema de creencias ni concepto de Dios, pero ahora ten\u00eda que saber qu\u00e9 era lo que hac\u00eda que algo llamado cristianismo fuera tan peligroso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kyung-Ja hab\u00eda sido detenida ya dos veces antes por cruzar ilegalmente a <a href=\"http:\/\/persecution.com\/es\/guiadeoracionglobal\/china\/\">China<\/a>. Esta vez, sin embargo, fue peor. En lugar de cumplir solo unos meses de \u00abreeducaci\u00f3n\u00bb en un campo de trabajo, soport\u00f3 repetidas torturas, muy probablemente a causa de la deserci\u00f3n de su hija.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras golpear brutalmente a Kyung-Ja durante dos meses, la guardia se dio cuenta de que la mujer no ten\u00eda ning\u00fan v\u00ednculo con los cristianos de <a href=\"http:\/\/persecution.com\/es\/guiadeoracionglobal\/corea-del-norte\/\">Corea del Norte<\/a>. Luego envi\u00f3 a Kyung-Ja, que ahora pesa unos fr\u00e1giles 63 kilos, a un campo de trabajo, pero se llev\u00f3 consigo sus preguntas sobre el cristianismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2014Oye, \u00bfqu\u00e9 es Dios? \u2014le pregunt\u00f3 a una compa\u00f1era de prisi\u00f3n que conoci\u00f3\u2014. \u00bfQu\u00e9 es la <a href=\"http:\/\/persecution.com\/es\/biblias\/?utm_campaign=bibles_es&amp;utm_source=ESSTORIES\">Biblia<\/a>?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2014Eso existe \u2014contest\u00f3 tranquilamente la prisionera\u2014. Hay un libro, pero no preguntes. \u00a1Shhh!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El miedo de la prisionera confirm\u00f3 la sospecha de Kyung-ja de que el cristianismo era una religi\u00f3n prohibida que solo segu\u00edan los criminales.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"what-was-meant-for-evil\">LO QUE FUE PENSADO PARA MAL<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Kyung-Ja pas\u00f3 los siguientes seis meses en el campo de trabajo (llamado <em>kyohwaso<\/em>) soportando trabajos agotadores y condiciones inhumanas. Ve\u00eda a otros reclusos morir todos los d\u00edas por las terribles condiciones o por las lesiones sufridas en las despiadadas palizas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kyung-Ja anhelaba la libertad. Su marido hab\u00eda muerto durante una de sus anteriores detenciones, y no quer\u00eda perderse de vivir cerca de su hija, que hab\u00eda desertado a Corea del Sur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n quer\u00eda salir para aprender m\u00e1s sobre el cristianismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras seis meses de trabajos forzados, Kyung-Ja fue liberada. Cree que las autoridades la liberaron porque les dijo la verdad sobre su viaje a <a href=\"http:\/\/persecution.com\/es\/guiadeoracionglobal\/china\/\">China<\/a>: se fue porque ten\u00eda que encontrar la forma de alimentar a su familia. En aquella \u00e9poca, muchas personas cruzaban la frontera con <a href=\"http:\/\/persecution.com\/es\/guiadeoracionglobal\/china\/\">China<\/a> para alimentar a sus familias, y a su regreso a <a href=\"http:\/\/persecution.com\/es\/guiadeoracionglobal\/corea-del-norte\/\">Corea del Norte<\/a> sol\u00edan ser \u00abreeducadas\u00bb con unos meses de trabajos forzados en lugar de ser castigadas m\u00e1s severamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La hija de Kyung-ja en Corea del Sur acab\u00f3 reuniendo suficiente dinero para ayudar a su madre a desertar y consigui\u00f3 que un pastor la ayudara. Entonces, durante una llamada telef\u00f3nica con su hija, Kyung-ja recibi\u00f3 por fin algunas respuestas a sus preguntas sobre el cristianismo: se enter\u00f3 de que la iglesia es real y que tambi\u00e9n lo es el Dios al que ahora adora. Kyung-ja pronto puso su fe en Jes\u00fas y encontr\u00f3 la verdadera libertad en el Dios del que hab\u00eda o\u00eddo hablar por primera vez mientras era golpeada por una guardia de la prisi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora que vive en Corea del Sur, Kyung-Ja nunca se pierde una reuni\u00f3n en la iglesia, y comparte con entusiasmo su testimonio con los dem\u00e1s. Aunque todav\u00eda se enfrenta a los efectos de su traum\u00e1tico encarcelamiento como la ansiedad, la depresi\u00f3n, las pesadillas y los latidos irregulares del coraz\u00f3n, sigue encontrando paz en Cristo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente participa en un programa patrocinado por VOM para discipular a los cristianos <a href=\"http:\/\/persecution.com\/es\/guiadeoracionglobal\/corea-del-norte\/\">norcoreanos<\/a> y los prepara para que les comuniquen el evangelio a los desertores <a href=\"http:\/\/persecution.com\/es\/guiadeoracionglobal\/corea-del-norte\/\">norcoreanos<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al reflexionar sobre c\u00f3mo su torturadora sembr\u00f3 en su coraz\u00f3n las semillas del evangelio, Kyung-ja est\u00e1 agradecida con Dios. Su amor por Cristo se hace m\u00e1s fuerte cada d\u00eda, y ahora est\u00e1 dispuesta a \u00abseguirlo hasta la muerte\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEn retrospectiva \u2014dijo\u2014, todo es por la gracia de Dios\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras Kyung-Ja luchaba por mantener la consciencia con la cabeza ensangrentada por los repetidos golpes de un garrote escuch\u00f3 a su carcelera gritar palabras que nunca hab\u00eda o\u00eddo en sus 56 a\u00f1os de vida: \u00abBiblia\u00bb, \u00abDios\u00bb, \u00abJes\u00fas\u00bb. Guardia de Corea del Norte: Evangelista por accidente Kyung-Ja entend\u00eda por qu\u00e9 la guardia la hab\u00eda interrogado sobre su \u00faltimo viaje a China y sobre la deserci\u00f3n de su hija a Corea del Sur, pero no pod\u00eda entender por qu\u00e9 segu\u00eda haciendo preguntas extra\u00f1as sobre algo llamado \u00abcristianismo\u00bb. \u00abLa primera vez que conoc\u00ed el cristianismo fue gracias a mi torturadora\u00bb, dijo Kyung-Ja. Las confusas y persistentes preguntas de la carcelera despertaron la curiosidad de Kyung-ja. En el momento de su detenci\u00f3n, no ten\u00eda ning\u00fan sistema de creencias ni concepto de Dios, pero ahora ten\u00eda que saber qu\u00e9 era lo que hac\u00eda que algo llamado cristianismo fuera tan peligroso. Kyung-Ja hab\u00eda sido detenida ya dos veces antes por cruzar ilegalmente a China. Esta vez, sin embargo, fue peor. En lugar de cumplir solo unos meses de \u00abreeducaci\u00f3n\u00bb en un campo de trabajo, soport\u00f3 repetidas torturas, muy probablemente a causa de la deserci\u00f3n de su hija. Tras golpear brutalmente a Kyung-Ja durante dos meses, la<\/p>\n","protected":false},"author":12,"featured_media":525,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[20,48],"class_list":["post-316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia","tag-china","tag-corea-del-norte","","tg-column-two"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una guardia norcoreana habla accidentalmente de Dios a una mujer presa - Historias<\/title>\n<meta name=\"description\" content=\"Tras golpear brutalmente a Kyung-Ja durante dos meses, la guardia se dio cuenta de que la mujer no ten\u00eda ning\u00fan v\u00ednculo con los cristianos...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.persecution.com\/es\/historias\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una guardia norcoreana habla accidentalmente de Dios a una mujer presa - Historias\" \/>\n<meta property=\"og:description\" content=\"Tras golpear brutalmente a Kyung-Ja durante dos meses, la guardia se dio cuenta de que la mujer no ten\u00eda ning\u00fan v\u00ednculo con los cristianos...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.persecution.com\/es\/historias\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\/\" \/>\n<meta property=\"og:site_name\" content=\"Historias\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-01T08:15:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-21T21:21:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/06\/nk_0303_034_pub.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1188\" \/>\n\t<meta property=\"og:image:height\" content=\"799\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"E Valenzuela\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/06\/nk_0303_034_pub.jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"E Valenzuela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\\\/\"},\"author\":{\"name\":\"E Valenzuela\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/#\\\/schema\\\/person\\\/ae000ea52969cef1249f5afb05ccb961\"},\"headline\":\"Una guardia norcoreana habla accidentalmente de Dios a una mujer presa\",\"datePublished\":\"2021-09-01T08:15:42+00:00\",\"dateModified\":\"2022-10-21T21:21:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\\\/\"},\"wordCount\":748,\"image\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/nk_0303_034_pub.jpeg\",\"keywords\":[\"China\",\"Corea Del Norte\"],\"articleSection\":[\"Historia\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\\\/\",\"url\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\\\/\",\"name\":\"Una guardia norcoreana habla accidentalmente de Dios a una mujer presa - Historias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/nk_0303_034_pub.jpeg\",\"datePublished\":\"2021-09-01T08:15:42+00:00\",\"dateModified\":\"2022-10-21T21:21:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/#\\\/schema\\\/person\\\/ae000ea52969cef1249f5afb05ccb961\"},\"description\":\"Tras golpear brutalmente a Kyung-Ja durante dos meses, la guardia se dio cuenta de que la mujer no ten\u00eda ning\u00fan v\u00ednculo con los cristianos...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/nk_0303_034_pub.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/nk_0303_034_pub.jpeg\",\"width\":1188,\"height\":799,\"caption\":\"North Korean outdoor labor camp view from above\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una guardia norcoreana habla accidentalmente de Dios a una mujer presa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/#website\",\"url\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/\",\"name\":\"Historias\",\"description\":\"La Voz de los M\u00e1rtires\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/#\\\/schema\\\/person\\\/ae000ea52969cef1249f5afb05ccb961\",\"name\":\"E Valenzuela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72e02a942ef259240205425b9749482f07b1b2fb64225b038b4531b157d191a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72e02a942ef259240205425b9749482f07b1b2fb64225b038b4531b157d191a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72e02a942ef259240205425b9749482f07b1b2fb64225b038b4531b157d191a7?s=96&d=mm&r=g\",\"caption\":\"E Valenzuela\"},\"url\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/author\\\/evalenzuelavom-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una guardia norcoreana habla accidentalmente de Dios a una mujer presa - Historias","description":"Tras golpear brutalmente a Kyung-Ja durante dos meses, la guardia se dio cuenta de que la mujer no ten\u00eda ning\u00fan v\u00ednculo con los cristianos...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.persecution.com\/es\/historias\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\/","og_locale":"es_MX","og_type":"article","og_title":"Una guardia norcoreana habla accidentalmente de Dios a una mujer presa - Historias","og_description":"Tras golpear brutalmente a Kyung-Ja durante dos meses, la guardia se dio cuenta de que la mujer no ten\u00eda ning\u00fan v\u00ednculo con los cristianos...","og_url":"https:\/\/www.persecution.com\/es\/historias\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\/","og_site_name":"Historias","article_published_time":"2021-09-01T08:15:42+00:00","article_modified_time":"2022-10-21T21:21:52+00:00","og_image":[{"width":1188,"height":799,"url":"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/06\/nk_0303_034_pub.jpeg","type":"image\/jpeg"}],"author":"E Valenzuela","twitter_card":"summary_large_image","twitter_image":"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/06\/nk_0303_034_pub.jpeg","twitter_misc":{"Escrito por":"E Valenzuela","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.persecution.com\/es\/historias\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\/#article","isPartOf":{"@id":"https:\/\/www.persecution.com\/es\/historias\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\/"},"author":{"name":"E Valenzuela","@id":"https:\/\/www.persecution.com\/es\/historias\/#\/schema\/person\/ae000ea52969cef1249f5afb05ccb961"},"headline":"Una guardia norcoreana habla accidentalmente de Dios a una mujer presa","datePublished":"2021-09-01T08:15:42+00:00","dateModified":"2022-10-21T21:21:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.persecution.com\/es\/historias\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\/"},"wordCount":748,"image":{"@id":"https:\/\/www.persecution.com\/es\/historias\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/06\/nk_0303_034_pub.jpeg","keywords":["China","Corea Del Norte"],"articleSection":["Historia"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.persecution.com\/es\/historias\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\/","url":"https:\/\/www.persecution.com\/es\/historias\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\/","name":"Una guardia norcoreana habla accidentalmente de Dios a una mujer presa - Historias","isPartOf":{"@id":"https:\/\/www.persecution.com\/es\/historias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.persecution.com\/es\/historias\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\/#primaryimage"},"image":{"@id":"https:\/\/www.persecution.com\/es\/historias\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/06\/nk_0303_034_pub.jpeg","datePublished":"2021-09-01T08:15:42+00:00","dateModified":"2022-10-21T21:21:52+00:00","author":{"@id":"https:\/\/www.persecution.com\/es\/historias\/#\/schema\/person\/ae000ea52969cef1249f5afb05ccb961"},"description":"Tras golpear brutalmente a Kyung-Ja durante dos meses, la guardia se dio cuenta de que la mujer no ten\u00eda ning\u00fan v\u00ednculo con los cristianos...","breadcrumb":{"@id":"https:\/\/www.persecution.com\/es\/historias\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.persecution.com\/es\/historias\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.persecution.com\/es\/historias\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\/#primaryimage","url":"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/06\/nk_0303_034_pub.jpeg","contentUrl":"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/06\/nk_0303_034_pub.jpeg","width":1188,"height":799,"caption":"North Korean outdoor labor camp view from above"},{"@type":"BreadcrumbList","@id":"https:\/\/www.persecution.com\/es\/historias\/una-guardia-norcoreana-habla-accidentalmente-de-dios-a-una-mujer-presa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.persecution.com\/es\/historias\/"},{"@type":"ListItem","position":2,"name":"Una guardia norcoreana habla accidentalmente de Dios a una mujer presa"}]},{"@type":"WebSite","@id":"https:\/\/www.persecution.com\/es\/historias\/#website","url":"https:\/\/www.persecution.com\/es\/historias\/","name":"Historias","description":"La Voz de los M\u00e1rtires","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.persecution.com\/es\/historias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.persecution.com\/es\/historias\/#\/schema\/person\/ae000ea52969cef1249f5afb05ccb961","name":"E Valenzuela","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/72e02a942ef259240205425b9749482f07b1b2fb64225b038b4531b157d191a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72e02a942ef259240205425b9749482f07b1b2fb64225b038b4531b157d191a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72e02a942ef259240205425b9749482f07b1b2fb64225b038b4531b157d191a7?s=96&d=mm&r=g","caption":"E Valenzuela"},"url":"https:\/\/www.persecution.com\/es\/historias\/author\/evalenzuelavom-org\/"}]}},"_links":{"self":[{"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/posts\/316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/comments?post=316"}],"version-history":[{"count":4,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/posts\/316\/revisions"}],"predecessor-version":[{"id":4343,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/posts\/316\/revisions\/4343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/media\/525"}],"wp:attachment":[{"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/media?parent=316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/categories?post=316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/tags?post=316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}