{"id":2784,"date":"2021-09-16T07:07:03","date_gmt":"2021-09-16T07:07:03","guid":{"rendered":"https:\/\/www.persecution.com\/es\/historias\/adult-children-reject-christian-mother\/"},"modified":"2022-10-20T20:39:44","modified_gmt":"2022-10-20T20:39:44","slug":"hijos-adultos-rechazan-a-madre-cristiana","status":"publish","type":"post","link":"https:\/\/www.persecution.com\/es\/historias\/hijos-adultos-rechazan-a-madre-cristiana\/","title":{"rendered":"Hijos adultos rechazan a madre cristiana"},"content":{"rendered":"<p>Despu\u00e9s de aceptar a Jesucristo como su Salvador, Suiy decidi\u00f3 llamar a su hijo y a su hija: \u00abLes dije que cre\u00ed en Dios, y que mi enfermedad desapareci\u00f3. Que mi salud era fuerte y que yo estaba muy feliz\u00bb. Sus hijos no recibieron bien la noticia. Su hija le dijo que dejara de creer en Dios o que ella ya no vendr\u00eda a visitarla, y que dejar\u00eda de amarla. Su hijo estaba incluso m\u00e1s enojado, y la repudi\u00f3 por completo. Sus dos hijos le dijeron que si sus empleadores descubr\u00edan que su madre era cristiana, los despedir\u00edan. \u00abDespu\u00e9s de escuchar estas palabras de mis hijos, me sent\u00ed desanimada y avergonzada \u2014dijo Suiy\u2014. Estoy vieja y todos mis ingresos provienen de mis hijos\u00bb. Llam\u00f3 a su pastor, quien la anim\u00f3 a permanecer fiel a Dios, sin importar las circunstancias. Despu\u00e9s, Suiy llam\u00f3 a sus hijos de nuevo y les dijo que nunca podr\u00eda dejar de creer en Dios, pero que siempre los amar\u00eda de la misma manera. A menudo, es dif\u00edcil para Suiy terminar el d\u00eda, y algunos d\u00edas no tiene suficiente para comer. Pide oraci\u00f3n para que sus hijos lleguen a conocer a Dios.<\/p>\n<p><a href=\"https:\/\/www.persecution.com\/es\/guiadeoracionglobal\/laos\/?_source_code=WBPGGPG20B\">Haz clic aqu\u00ed<\/a> para informarte sobre la persecuci\u00f3n de los cristianos en <a href=\"https:\/\/www.persecution.com\/es\/guiadeoracionglobal\/laos\/?_source_code=WBPGGPG20B\">Laos<\/a> y saber c\u00f3mo orar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de aceptar a Jesucristo como su Salvador, Suiy decidi\u00f3 llamar a su hijo y a su hija: \u00abLes dije que cre\u00ed en Dios, y que mi enfermedad desapareci\u00f3. Que mi salud era fuerte y que yo estaba muy feliz\u00bb. Sus hijos no recibieron bien la noticia. Su hija le dijo que dejara de creer en Dios o que ella ya no vendr\u00eda a visitarla, y que dejar\u00eda de amarla. Su hijo estaba incluso m\u00e1s enojado, y la repudi\u00f3 por completo. Sus dos hijos le dijeron que si sus empleadores descubr\u00edan que su madre era cristiana, los despedir\u00edan. \u00abDespu\u00e9s de escuchar estas palabras de mis hijos, me sent\u00ed desanimada y avergonzada \u2014dijo Suiy\u2014. Estoy vieja y todos mis ingresos provienen de mis hijos\u00bb. Llam\u00f3 a su pastor, quien la anim\u00f3 a permanecer fiel a Dios, sin importar las circunstancias. Despu\u00e9s, Suiy llam\u00f3 a sus hijos de nuevo y les dijo que nunca podr\u00eda dejar de creer en Dios, pero que siempre los amar\u00eda de la misma manera. A menudo, es dif\u00edcil para Suiy terminar el d\u00eda, y algunos d\u00edas no tiene suficiente para comer. Pide oraci\u00f3n para que sus hijos lleguen a conocer a Dios. Haz clic aqu\u00ed para informarte<\/p>\n","protected":false},"author":12,"featured_media":181,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79],"tags":[37],"class_list":["post-2784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-oracion","tag-laos","","tg-column-two"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hijos adultos rechazan a madre cristiana - Historias<\/title>\n<meta name=\"description\" content=\"Llam\u00f3 a su pastor, quien la anim\u00f3 a permanecer fiel a Dios, sin importar las circunstancias.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.persecution.com\/es\/historias\/hijos-adultos-rechazan-a-madre-cristiana\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hijos adultos rechazan a madre cristiana - Historias\" \/>\n<meta property=\"og:description\" content=\"Llam\u00f3 a su pastor, quien la anim\u00f3 a permanecer fiel a Dios, sin importar las circunstancias.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.persecution.com\/es\/historias\/hijos-adultos-rechazan-a-madre-cristiana\/\" \/>\n<meta property=\"og:site_name\" content=\"Historias\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-16T07:07:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-20T20:39:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/05\/VOM-Stories-iCommit-PlaceholderV2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"978\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"E Valenzuela\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"E Valenzuela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/hijos-adultos-rechazan-a-madre-cristiana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/hijos-adultos-rechazan-a-madre-cristiana\\\/\"},\"author\":{\"name\":\"E Valenzuela\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/#\\\/schema\\\/person\\\/ae000ea52969cef1249f5afb05ccb961\"},\"headline\":\"Hijos adultos rechazan a madre cristiana\",\"datePublished\":\"2021-09-16T07:07:03+00:00\",\"dateModified\":\"2022-10-20T20:39:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/hijos-adultos-rechazan-a-madre-cristiana\\\/\"},\"wordCount\":234,\"image\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/hijos-adultos-rechazan-a-madre-cristiana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/VOM-Stories-iCommit-PlaceholderV2.jpg\",\"keywords\":[\"Laos\"],\"articleSection\":[\"Oraci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/hijos-adultos-rechazan-a-madre-cristiana\\\/\",\"url\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/hijos-adultos-rechazan-a-madre-cristiana\\\/\",\"name\":\"Hijos adultos rechazan a madre cristiana - Historias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/hijos-adultos-rechazan-a-madre-cristiana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/hijos-adultos-rechazan-a-madre-cristiana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/VOM-Stories-iCommit-PlaceholderV2.jpg\",\"datePublished\":\"2021-09-16T07:07:03+00:00\",\"dateModified\":\"2022-10-20T20:39:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/#\\\/schema\\\/person\\\/ae000ea52969cef1249f5afb05ccb961\"},\"description\":\"Llam\u00f3 a su pastor, quien la anim\u00f3 a permanecer fiel a Dios, sin importar las circunstancias.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/hijos-adultos-rechazan-a-madre-cristiana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/hijos-adultos-rechazan-a-madre-cristiana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/hijos-adultos-rechazan-a-madre-cristiana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/VOM-Stories-iCommit-PlaceholderV2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/VOM-Stories-iCommit-PlaceholderV2.jpg\",\"width\":978,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/hijos-adultos-rechazan-a-madre-cristiana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hijos adultos rechazan a madre cristiana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/#website\",\"url\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/\",\"name\":\"Historias\",\"description\":\"La Voz de los M\u00e1rtires\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/#\\\/schema\\\/person\\\/ae000ea52969cef1249f5afb05ccb961\",\"name\":\"E Valenzuela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72e02a942ef259240205425b9749482f07b1b2fb64225b038b4531b157d191a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72e02a942ef259240205425b9749482f07b1b2fb64225b038b4531b157d191a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72e02a942ef259240205425b9749482f07b1b2fb64225b038b4531b157d191a7?s=96&d=mm&r=g\",\"caption\":\"E Valenzuela\"},\"url\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/author\\\/evalenzuelavom-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hijos adultos rechazan a madre cristiana - Historias","description":"Llam\u00f3 a su pastor, quien la anim\u00f3 a permanecer fiel a Dios, sin importar las circunstancias.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.persecution.com\/es\/historias\/hijos-adultos-rechazan-a-madre-cristiana\/","og_locale":"es_MX","og_type":"article","og_title":"Hijos adultos rechazan a madre cristiana - Historias","og_description":"Llam\u00f3 a su pastor, quien la anim\u00f3 a permanecer fiel a Dios, sin importar las circunstancias.","og_url":"https:\/\/www.persecution.com\/es\/historias\/hijos-adultos-rechazan-a-madre-cristiana\/","og_site_name":"Historias","article_published_time":"2021-09-16T07:07:03+00:00","article_modified_time":"2022-10-20T20:39:44+00:00","og_image":[{"width":978,"height":640,"url":"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/05\/VOM-Stories-iCommit-PlaceholderV2.jpg","type":"image\/jpeg"}],"author":"E Valenzuela","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"E Valenzuela","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.persecution.com\/es\/historias\/hijos-adultos-rechazan-a-madre-cristiana\/#article","isPartOf":{"@id":"https:\/\/www.persecution.com\/es\/historias\/hijos-adultos-rechazan-a-madre-cristiana\/"},"author":{"name":"E Valenzuela","@id":"https:\/\/www.persecution.com\/es\/historias\/#\/schema\/person\/ae000ea52969cef1249f5afb05ccb961"},"headline":"Hijos adultos rechazan a madre cristiana","datePublished":"2021-09-16T07:07:03+00:00","dateModified":"2022-10-20T20:39:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.persecution.com\/es\/historias\/hijos-adultos-rechazan-a-madre-cristiana\/"},"wordCount":234,"image":{"@id":"https:\/\/www.persecution.com\/es\/historias\/hijos-adultos-rechazan-a-madre-cristiana\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/05\/VOM-Stories-iCommit-PlaceholderV2.jpg","keywords":["Laos"],"articleSection":["Oraci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.persecution.com\/es\/historias\/hijos-adultos-rechazan-a-madre-cristiana\/","url":"https:\/\/www.persecution.com\/es\/historias\/hijos-adultos-rechazan-a-madre-cristiana\/","name":"Hijos adultos rechazan a madre cristiana - Historias","isPartOf":{"@id":"https:\/\/www.persecution.com\/es\/historias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.persecution.com\/es\/historias\/hijos-adultos-rechazan-a-madre-cristiana\/#primaryimage"},"image":{"@id":"https:\/\/www.persecution.com\/es\/historias\/hijos-adultos-rechazan-a-madre-cristiana\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/05\/VOM-Stories-iCommit-PlaceholderV2.jpg","datePublished":"2021-09-16T07:07:03+00:00","dateModified":"2022-10-20T20:39:44+00:00","author":{"@id":"https:\/\/www.persecution.com\/es\/historias\/#\/schema\/person\/ae000ea52969cef1249f5afb05ccb961"},"description":"Llam\u00f3 a su pastor, quien la anim\u00f3 a permanecer fiel a Dios, sin importar las circunstancias.","breadcrumb":{"@id":"https:\/\/www.persecution.com\/es\/historias\/hijos-adultos-rechazan-a-madre-cristiana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.persecution.com\/es\/historias\/hijos-adultos-rechazan-a-madre-cristiana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.persecution.com\/es\/historias\/hijos-adultos-rechazan-a-madre-cristiana\/#primaryimage","url":"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/05\/VOM-Stories-iCommit-PlaceholderV2.jpg","contentUrl":"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/05\/VOM-Stories-iCommit-PlaceholderV2.jpg","width":978,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.persecution.com\/es\/historias\/hijos-adultos-rechazan-a-madre-cristiana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.persecution.com\/es\/historias\/"},{"@type":"ListItem","position":2,"name":"Hijos adultos rechazan a madre cristiana"}]},{"@type":"WebSite","@id":"https:\/\/www.persecution.com\/es\/historias\/#website","url":"https:\/\/www.persecution.com\/es\/historias\/","name":"Historias","description":"La Voz de los M\u00e1rtires","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.persecution.com\/es\/historias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.persecution.com\/es\/historias\/#\/schema\/person\/ae000ea52969cef1249f5afb05ccb961","name":"E Valenzuela","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/72e02a942ef259240205425b9749482f07b1b2fb64225b038b4531b157d191a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72e02a942ef259240205425b9749482f07b1b2fb64225b038b4531b157d191a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72e02a942ef259240205425b9749482f07b1b2fb64225b038b4531b157d191a7?s=96&d=mm&r=g","caption":"E Valenzuela"},"url":"https:\/\/www.persecution.com\/es\/historias\/author\/evalenzuelavom-org\/"}]}},"_links":{"self":[{"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/posts\/2784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/comments?post=2784"}],"version-history":[{"count":1,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/posts\/2784\/revisions"}],"predecessor-version":[{"id":4072,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/posts\/2784\/revisions\/4072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/media\/181"}],"wp:attachment":[{"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/media?parent=2784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/categories?post=2784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/tags?post=2784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}