{"id":2678,"date":"2021-09-02T07:07:02","date_gmt":"2021-09-02T07:07:02","guid":{"rendered":"https:\/\/www.persecution.com\/es\/historias\/displaced-christian-encouraged-by-medical-help\/"},"modified":"2022-10-21T21:16:34","modified_gmt":"2022-10-21T21:16:34","slug":"cristiano-desplazado-se-siente-alentado-por-ayuda-medica","status":"publish","type":"post","link":"https:\/\/www.persecution.com\/es\/historias\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\/","title":{"rendered":"Cristiano desplazado se siente alentado por ayuda m\u00e9dica"},"content":{"rendered":"<p>Emmanuel Dounia vive en un campamento de desplazados internos en la <a href=\"https:\/\/www.persecution.com\/es\/guiadeoracionglobal\/republica-centroafricana\/?_source_code=WBPGGPG20B\">Rep\u00fablica Centroafricana<\/a>. Fue expulsado de su casa despu\u00e9s de que los rebeldes de Seleka atacaran su aldea, quemaran su casa y agredieran sexualmente a su esposa frente a \u00e9l. Sus hijos murieron por disparos de ca\u00f1\u00f3n, y \u00e9l tambi\u00e9n fue torturado. Desde que vive en el campamento, Emmanuel ha tenido dificultades con su salud, y el acceso a los medicamentos necesarios ha sido limitado. Recientemente, con la ayuda de VOM, Emmanuel recibi\u00f3 las medicinas que necesitaba, y su paz ha sido restaurada. \u00abMi alegr\u00eda es inmensa. Que sea alabado el nombre de Dios. Gracias, hoy tengo paz de coraz\u00f3n\u00bb, dijo. Aunque ha sufrido mucho, su fe no ha flaqueado, ya que ha encontrado consuelo en las Escrituras. \u00abLo que m\u00e1s me consuela es la Palabra de Dios \u2014dijo\u2014. En nuestro campamento, nunca dejamos de reunirnos para hablar sobre la palabra de Dios\u00bb. Ore para que Emmanuel contin\u00fae encontrando fortaleza y aliento en la Palabra de Dios a medida que su salud se recupera. Ore para que su testimonio llegue a otros dentro del campamento con el amor de Dios.<\/p>\n<p><a href=\"https:\/\/www.persecution.com\/es\/guiadeoracionglobal\/republica-centroafricana\/\">Haz clic aqu\u00ed<\/a> para averiguar sobre la persecuci\u00f3n cristiana en la Rep\u00fablica Centroafricana y saber c\u00f3mo orar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Emmanuel Dounia vive en un campamento de desplazados internos en la Rep\u00fablica Centroafricana. Fue expulsado de su casa despu\u00e9s de que los rebeldes de Seleka atacaran su aldea, quemaran su casa y agredieran sexualmente a su esposa frente a \u00e9l. Sus hijos murieron por disparos de ca\u00f1\u00f3n, y \u00e9l tambi\u00e9n fue torturado. Desde que vive en el campamento, Emmanuel ha tenido dificultades con su salud, y el acceso a los medicamentos necesarios ha sido limitado. Recientemente, con la ayuda de VOM, Emmanuel recibi\u00f3 las medicinas que necesitaba, y su paz ha sido restaurada. \u00abMi alegr\u00eda es inmensa. Que sea alabado el nombre de Dios. Gracias, hoy tengo paz de coraz\u00f3n\u00bb, dijo. Aunque ha sufrido mucho, su fe no ha flaqueado, ya que ha encontrado consuelo en las Escrituras. \u00abLo que m\u00e1s me consuela es la Palabra de Dios \u2014dijo\u2014. En nuestro campamento, nunca dejamos de reunirnos para hablar sobre la palabra de Dios\u00bb. Ore para que Emmanuel contin\u00fae encontrando fortaleza y aliento en la Palabra de Dios a medida que su salud se recupera. Ore para que su testimonio llegue a otros dentro del campamento con el amor de Dios. Haz clic aqu\u00ed para averiguar sobre la persecuci\u00f3n cristiana en<\/p>\n","protected":false},"author":12,"featured_media":181,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79],"tags":[19],"class_list":["post-2678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-oracion","tag-republica-centroafricana","","tg-column-two"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cristiano desplazado se siente alentado por ayuda m\u00e9dica - Historias<\/title>\n<meta name=\"description\" content=\"Fue expulsado de su casa despu\u00e9s de que los rebeldes de Seleka atacaran su aldea, quemaran su casa y agredieran sexualmente a su esposa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.persecution.com\/es\/historias\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cristiano desplazado se siente alentado por ayuda m\u00e9dica - Historias\" \/>\n<meta property=\"og:description\" content=\"Fue expulsado de su casa despu\u00e9s de que los rebeldes de Seleka atacaran su aldea, quemaran su casa y agredieran sexualmente a su esposa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.persecution.com\/es\/historias\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\/\" \/>\n<meta property=\"og:site_name\" content=\"Historias\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-02T07:07:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-21T21:16:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/05\/VOM-Stories-iCommit-PlaceholderV2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"978\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"E Valenzuela\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"E Valenzuela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\\\/\"},\"author\":{\"name\":\"E Valenzuela\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/#\\\/schema\\\/person\\\/ae000ea52969cef1249f5afb05ccb961\"},\"headline\":\"Cristiano desplazado se siente alentado por ayuda m\u00e9dica\",\"datePublished\":\"2021-09-02T07:07:02+00:00\",\"dateModified\":\"2022-10-21T21:16:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\\\/\"},\"wordCount\":227,\"image\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/VOM-Stories-iCommit-PlaceholderV2.jpg\",\"keywords\":[\"Rep\u00fablica Centroafricana\"],\"articleSection\":[\"Oraci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\\\/\",\"url\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\\\/\",\"name\":\"Cristiano desplazado se siente alentado por ayuda m\u00e9dica - Historias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/VOM-Stories-iCommit-PlaceholderV2.jpg\",\"datePublished\":\"2021-09-02T07:07:02+00:00\",\"dateModified\":\"2022-10-21T21:16:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/#\\\/schema\\\/person\\\/ae000ea52969cef1249f5afb05ccb961\"},\"description\":\"Fue expulsado de su casa despu\u00e9s de que los rebeldes de Seleka atacaran su aldea, quemaran su casa y agredieran sexualmente a su esposa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/VOM-Stories-iCommit-PlaceholderV2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/VOM-Stories-iCommit-PlaceholderV2.jpg\",\"width\":978,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cristiano desplazado se siente alentado por ayuda m\u00e9dica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/#website\",\"url\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/\",\"name\":\"Historias\",\"description\":\"La Voz de los M\u00e1rtires\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/#\\\/schema\\\/person\\\/ae000ea52969cef1249f5afb05ccb961\",\"name\":\"E Valenzuela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72e02a942ef259240205425b9749482f07b1b2fb64225b038b4531b157d191a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72e02a942ef259240205425b9749482f07b1b2fb64225b038b4531b157d191a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72e02a942ef259240205425b9749482f07b1b2fb64225b038b4531b157d191a7?s=96&d=mm&r=g\",\"caption\":\"E Valenzuela\"},\"url\":\"https:\\\/\\\/www.persecution.com\\\/es\\\/historias\\\/author\\\/evalenzuelavom-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cristiano desplazado se siente alentado por ayuda m\u00e9dica - Historias","description":"Fue expulsado de su casa despu\u00e9s de que los rebeldes de Seleka atacaran su aldea, quemaran su casa y agredieran sexualmente a su esposa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.persecution.com\/es\/historias\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\/","og_locale":"es_MX","og_type":"article","og_title":"Cristiano desplazado se siente alentado por ayuda m\u00e9dica - Historias","og_description":"Fue expulsado de su casa despu\u00e9s de que los rebeldes de Seleka atacaran su aldea, quemaran su casa y agredieran sexualmente a su esposa.","og_url":"https:\/\/www.persecution.com\/es\/historias\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\/","og_site_name":"Historias","article_published_time":"2021-09-02T07:07:02+00:00","article_modified_time":"2022-10-21T21:16:34+00:00","og_image":[{"width":978,"height":640,"url":"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/05\/VOM-Stories-iCommit-PlaceholderV2.jpg","type":"image\/jpeg"}],"author":"E Valenzuela","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"E Valenzuela","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.persecution.com\/es\/historias\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\/#article","isPartOf":{"@id":"https:\/\/www.persecution.com\/es\/historias\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\/"},"author":{"name":"E Valenzuela","@id":"https:\/\/www.persecution.com\/es\/historias\/#\/schema\/person\/ae000ea52969cef1249f5afb05ccb961"},"headline":"Cristiano desplazado se siente alentado por ayuda m\u00e9dica","datePublished":"2021-09-02T07:07:02+00:00","dateModified":"2022-10-21T21:16:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.persecution.com\/es\/historias\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\/"},"wordCount":227,"image":{"@id":"https:\/\/www.persecution.com\/es\/historias\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/05\/VOM-Stories-iCommit-PlaceholderV2.jpg","keywords":["Rep\u00fablica Centroafricana"],"articleSection":["Oraci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.persecution.com\/es\/historias\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\/","url":"https:\/\/www.persecution.com\/es\/historias\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\/","name":"Cristiano desplazado se siente alentado por ayuda m\u00e9dica - Historias","isPartOf":{"@id":"https:\/\/www.persecution.com\/es\/historias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.persecution.com\/es\/historias\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\/#primaryimage"},"image":{"@id":"https:\/\/www.persecution.com\/es\/historias\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/05\/VOM-Stories-iCommit-PlaceholderV2.jpg","datePublished":"2021-09-02T07:07:02+00:00","dateModified":"2022-10-21T21:16:34+00:00","author":{"@id":"https:\/\/www.persecution.com\/es\/historias\/#\/schema\/person\/ae000ea52969cef1249f5afb05ccb961"},"description":"Fue expulsado de su casa despu\u00e9s de que los rebeldes de Seleka atacaran su aldea, quemaran su casa y agredieran sexualmente a su esposa.","breadcrumb":{"@id":"https:\/\/www.persecution.com\/es\/historias\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.persecution.com\/es\/historias\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.persecution.com\/es\/historias\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\/#primaryimage","url":"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/05\/VOM-Stories-iCommit-PlaceholderV2.jpg","contentUrl":"https:\/\/assets.persecution.com\/es\/historias\/wp-content\/uploads\/2021\/05\/VOM-Stories-iCommit-PlaceholderV2.jpg","width":978,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.persecution.com\/es\/historias\/cristiano-desplazado-se-siente-alentado-por-ayuda-medica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.persecution.com\/es\/historias\/"},{"@type":"ListItem","position":2,"name":"Cristiano desplazado se siente alentado por ayuda m\u00e9dica"}]},{"@type":"WebSite","@id":"https:\/\/www.persecution.com\/es\/historias\/#website","url":"https:\/\/www.persecution.com\/es\/historias\/","name":"Historias","description":"La Voz de los M\u00e1rtires","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.persecution.com\/es\/historias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.persecution.com\/es\/historias\/#\/schema\/person\/ae000ea52969cef1249f5afb05ccb961","name":"E Valenzuela","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/72e02a942ef259240205425b9749482f07b1b2fb64225b038b4531b157d191a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72e02a942ef259240205425b9749482f07b1b2fb64225b038b4531b157d191a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72e02a942ef259240205425b9749482f07b1b2fb64225b038b4531b157d191a7?s=96&d=mm&r=g","caption":"E Valenzuela"},"url":"https:\/\/www.persecution.com\/es\/historias\/author\/evalenzuelavom-org\/"}]}},"_links":{"self":[{"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/posts\/2678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/comments?post=2678"}],"version-history":[{"count":2,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/posts\/2678\/revisions"}],"predecessor-version":[{"id":4341,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/posts\/2678\/revisions\/4341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/media\/181"}],"wp:attachment":[{"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/media?parent=2678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/categories?post=2678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.persecution.com\/es\/historias\/wp-json\/wp\/v2\/tags?post=2678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}